{"id":5022,"date":"2020-12-06T20:51:59","date_gmt":"2020-12-06T20:51:59","guid":{"rendered":"https:\/\/nemiran.com\/roj\/?page_id=5022"},"modified":"2021-04-09T07:21:56","modified_gmt":"2021-04-09T07:21:56","slug":"janbakhtegan","status":"publish","type":"page","link":"https:\/\/nemiran.com\/roj\/fa\/janbakhtegan","title":{"rendered":"\u062c\u0627\u0646\u0628\u0627\u062e\u062a\u06af\u0627\u0646"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5022\" class=\"elementor elementor-5022\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1261d56c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1261d56c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-20ac0018\" data-id=\"20ac0018\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c0de4d elementor-widget elementor-widget-heading\" data-id=\"9c0de4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0633\u0627\u0645\u06cc \u0648 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u06d5 \u0627\u0639\u062f\u0627\u0645\u200c\u0634\u062f\u06af\u0627\u0646\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5dddcc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f5dddcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ded70b3 elementor-widget elementor-widget-image\" data-id=\"ded70b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1676\" height=\"300\" src=\"https:\/\/nemiran.com\/roj\/gloaptim\/2021\/01\/nemiran-lesedaredrawan-fars.gif\" class=\"attachment-full size-full wp-image-5027\" alt=\"Nemiran lesedaredrawan fars\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f06d9be elementor-widget elementor-widget-text-editor\" data-id=\"f06d9be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0633\u0631\u0627\u0633\u0631 \u0645\u0631\u062f\u0645 \u06a9\u0631\u062f\u0633\u062a\u0627\u0646 \u0627\u0632 \u0627\u06cc\u0644\u0627\u0645 \u062a\u0627 \u0645\u0627\u06a9\u0648 \u0648 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0633\u0631 \u06a9\u0627\u0631 \u0622\u0645\u062f\u0646 \u0631\u0698\u06cc\u0645 \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0635\u062f\u0647\u0627 \u0646\u0641\u0631 \u0628\u06cc\u06af\u0646\u0627\u0647 \u0627\u0639\u062f\u0627\u0645 \u0634\u062f\u06d5\u0627\u0646\u062f. \u06a9\u0634\u062a\u0627\u0631\u0647\u0627\u06cc \u062f\u0633\u062a\u0647 \u062c\u0645\u0639\u06cc \u06a9\u0647 \u0628\u0647 \u0634\u06cc\u0648\u0647\u200c\u06cc \u0633\u06cc\u0633\u062a\u06cc\u0645\u0627\u062a\u06cc\u06a9 \u0648 \u0628\u0631\u0646\u0627\u0645\u06d5\u0631\u06cc\u0632\u06cc \u0634\u062f\u0647 \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u060c \u0647\u06cc\u0686 \u06af\u0648\u0646\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648\u0627\u0636\u062d \u062f\u0631\u0628\u0627\u0631\u06d5 \u0627\u06cc\u0646 \u062c\u0646\u0627\u06cc\u062a\u0647\u0627 \u062a\u0627 \u0628\u06d5 \u0627\u0645\u0631\u0648\u0632 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0627\u0632 \u0633\u0631\u0646\u0648\u0634\u062a \u0627\u06cc\u0646 \u062c\u0648\u0627\u0646\u0627\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 \u0646\u06cc\u0633\u062a. \u06a9\u0633\u06cc \u0646\u0645\u06cc\u062f\u0627\u0646\u062f \u0645\u062a\u0648\u0644\u062f \u06a9\u062c\u0627 \u0647\u0633\u062a\u0646\u062f\u061f \u0627\u0632 \u0686\u0647 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0627\u06cc \u0647\u0633\u062a\u0646\u062f\u061f \u0632\u0646\u062f\u06af\u06cc\u0634\u0627\u0646 \u0686\u06af\u0648\u0646\u0647 \u0628\u0648\u062f\u0647\u061f \u0686\u06af\u0648\u0646\u06d5 \u0628\u0627\u0632\u062f\u0627\u0634\u062a \u0634\u062f\u06d5\u0627\u0646\u062f\u061f \u0622\u062e\u0631\u06cc\u0646 \u0631\u0648\u0632\u0647\u0627\u06cc \u0639\u0645\u0631\u0634\u0627\u0646 \u062f\u0631 \u0632\u0646\u062f\u0627\u0646 \u0686\u06af\u0648\u0646\u0647 \u0628\u0648\u062f\u0647 \u0648 \u062f\u0631 \u0631\u0648\u0632\u0647\u0627\u06cc \u0622\u062e\u0631 \u0632\u0646\u062f\u06af\u06cc\u0634\u0627\u0646 \u0686\u0647 \u0628\u0647 \u0633\u0631\u0634\u0627\u0646 \u0622\u0645\u062f\u0647\u060c \u06a9\u06cc \u0648\u06a9\u062c\u0627 \u0627\u0639\u062f\u0627\u0645 \u0634\u062f\u0647 \u0627\u0646\u062f \u06cc\u0627 \u0645\u0641\u0642\u0648\u062f\u0634\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f\u061f \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062e\u0627\u0637\u0631 \u0648\u0638\u06cc\u0641\u0647 \u06cc \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0627\u06cc\u0646 \u062c\u0627\u0646\u0628\u0627\u062e\u062a\u06af\u0627\u0646 \u0648\u0647\u0645\u0686\u0646\u06cc\u0646 \u0648\u0638\u06cc\u0641\u0647 \u0647\u0645\u0647 \u0622\u0646 \u06a9\u0633\u0627\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u0631\u0627\u062c\u0639 \u0628\u06d5 \u0632\u0646\u062f\u06af\u06cc \u0648 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0639\u0632\u06cc\u0632\u0627\u0646 \u062f\u0627\u0631\u0646\u062f\u060c \u0631\u0627 \u0628\u0647 \u0645\u0627 \u062a\u062d\u0648\u06cc\u0644 \u0628\u062f\u0647\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u0645 \u0627\u06cc\u0646\u062c\u0627 \u062b\u0628\u062a \u0648\u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u0645. \u0645\u0627 \u0646\u0633\u0644 \u0627\u0645\u0631\u0648\u0632 \u062a\u0646\u0647\u0627 \u06a9\u0633\u0627\u0646\u06cc \u0647\u0633\u062a\u06cc\u0645 \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0627\u06cc\u0646 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0648 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627 \u0631\u0627 \u0628\u06d5 \u0646\u06af\u0627\u0631\u0634 \u062f\u0631\u0622\u0648\u0631\u06cc\u0645. \u062b\u0628\u062a \u0627\u06cc\u0646 \u0648\u0642\u0627\u06cc\u0639 \u0628\u0627\u0639\u062b \u0645\u06cc\u0634\u0648\u062f \u06a9\u06d5 \u062c\u0646\u0627\u06cc\u062a\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0631\u0698\u06cc\u0645 \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u0634\u0648\u0646\u062f. \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0647\u0645 \u0627\u06af\u0631 \u0627\u06cc\u0646 \u0631\u0698\u06cc\u0645 \u0646\u0627\u0628\u0648\u062f \u0634\u0648\u062f \u0622\u0646 \u0645\u0648\u0642\u0639 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u0631 \u0639\u0644\u06cc\u06d5 \u0622\u0646\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631\u0627\u06cc\u0646 \u062c\u0646\u0627\u06cc\u062a\u0647\u0627 \u062f\u0633\u062a \u062f\u0627\u0634\u062a\u06d5\u0627\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645. \u0628\u0647 \u063a\u06cc\u0631\u0627\u0632\u0627\u06cc\u0646 \u0627\u0645\u06cc\u062f \u0627\u0633\u062a \u06a9\u06d5 \u0645\u0627\u0646\u0639\u06cc \u0634\u0648\u062f \u0628\u0631\u0627\u06cc \u062f\u0648\u0628\u0627\u0631\u0647 \u0634\u062f\u0646 \u0686\u0646\u06cc\u0646 \u0631\u0648\u06cc\u062f\u0627\u062f\u0647\u0627\u06cc\u06cc.<\/p><p>\u062f\u0633\u062a \u06cc\u0627\u0631\u06cc \u062f\u0631\u0627\u0632 \u0645\u06cc\u06a9\u0646\u06cc\u0645 \u0628\u06d5 \u0647\u0645\u0647 \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0647\u0631\u06af\u0648\u0646\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc \u0627\u0632 \u0642\u0628\u06cc\u0644 \u062c\u0645\u0639 \u06a9\u0631\u062f\u0646 \u0632\u0646\u062f\u06af\u06cc \u0646\u0627\u0645\u0647 \u0627\u06cc\u0646 \u0627\u0639\u062f\u0627\u0645 \u0634\u062f\u06af\u0627\u0646 \u0648\u0645\u0641\u0642\u0648\u062f\u0634\u062f\u06af\u0627\u0646 \u0631\u0627 \u062f\u0627\u0631\u0646\u062f\u060c\u0628\u0631\u0627\u06cc \u0645\u0627 \u0627\u0631\u0633\u0627\u0644 \u06a9\u0646\u0646\u062f.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a5f92c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a5f92c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ebcdcd6\" data-id=\"ebcdcd6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2978ca1 elementor-widget elementor-widget-shortcode\" data-id=\"2978ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t\t\t\t\t<style>\r\n\t\t\t\t<style>\r\n#wpsm_accordion_5031 .wpsm_panel-heading{\r\n\tpadding:0px !important;\r\n}\r\n#wpsm_accordion_5031 .wpsm_panel-title {\r\n\tmargin:0px !important; \r\n\ttext-transform:none !important;\r\n\tline-height: 1 !important;\r\n}\r\n#wpsm_accordion_5031 .wpsm_panel-title a{\r\n\ttext-decoration:none;\r\n\toverflow:hidden;\r\n\tdisplay:block;\r\n\tpadding:0px;\r\n\tfont-size: 20px !important;\r\n\tfont-family: Open Sans !important;\r\n\tcolor:#000000 !important;\r\n\tborder-bottom:0px !important;\r\n}\r\n\r\n#wpsm_accordion_5031 .wpsm_panel-title a:focus {\r\noutline: 0px !important;\r\n}\r\n\r\n#wpsm_accordion_5031 .wpsm_panel-title a:hover, #wpsm_accordion_5031 .wpsm_panel-title a:focus {\r\n\tcolor:#000000 !important;\r\n}\r\n#wpsm_accordion_5031 .acc-a{\r\n\tcolor: #000000 !important;\r\n\tbackground-color:#e8e8e8 !important;\r\n\tborder-color: #ddd;\r\n}\r\n#wpsm_accordion_5031 .wpsm_panel-default > .wpsm_panel-heading{\r\n\tcolor: #000000 !important;\r\n\tbackground-color: #e8e8e8 !important;\r\n\tborder-color: #e8e8e8 !important;\r\n\tborder-top-left-radius: 0px;\r\n\tborder-top-right-radius: 0px;\r\n}\r\n#wpsm_accordion_5031 .wpsm_panel-default {\r\n\t\tborder:1px solid transparent !important;\r\n\t}\r\n#wpsm_accordion_5031 {\r\n\tmargin-bottom: 20px;\r\n\toverflow: hidden;\r\n\tfloat: none;\r\n\twidth: 100%;\r\n\tdisplay: block;\r\n}\r\n#wpsm_accordion_5031 .ac_title_class{\r\n\tdisplay: block;\r\n\tpadding-top: 12px;\r\n\tpadding-bottom: 12px;\r\n\tpadding-left: 15px;\r\n\tpadding-right: 15px;\r\n}\r\n#wpsm_accordion_5031  .wpsm_panel {\r\n\toverflow:hidden;\r\n\t-webkit-box-shadow: 0 0px 0px rgba(0, 0, 0, .05);\r\n\tbox-shadow: 0 0px 0px rgba(0, 0, 0, .05);\r\n\t\tborder-radius: 4px;\r\n\t}\r\n#wpsm_accordion_5031  .wpsm_panel + .wpsm_panel {\r\n\t\tmargin-top: 5px;\r\n\t}\r\n#wpsm_accordion_5031  .wpsm_panel-body{\r\n\tbackground-color:#ffffff !important;\r\n\tcolor:#000000 !important;\r\n\tborder-top-color: #e8e8e8 !important;\r\n\tfont-size:18px !important;\r\n\tfont-family: Open Sans !important;\r\n\toverflow: hidden;\r\n\t\tborder: 2px solid #e8e8e8 !important;\r\n\t}\r\n\r\n#wpsm_accordion_5031 .ac_open_cl_icon{\r\n\tbackground-color:#e8e8e8 !important;\r\n\tcolor: #000000 !important;\r\n\tfloat:right !important;\r\n\tpadding-top: 12px !important;\r\n\tpadding-bottom: 12px !important;\r\n\tline-height: 1.0 !important;\r\n\tpadding-left: 15px !important;\r\n\tpadding-right: 15px !important;\r\n\tdisplay: inline-block !important;\r\n}\r\n\r\n\t\t\t\r\n\t\t\t<\/style>\t\r\n\t\t\t<\/style>\r\n\t\t\t<div class=\"wpsm_panel-group\" id=\"wpsm_accordion_5031\" >\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse1\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0665\u0668\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse1\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_10952\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"10952\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0665\u0668\"            id=\"footable_10952\"\n           data-unique_identifier=\"ninja_table_unique_id_1002753620_10952\"\n           class=\" foo-table ninja_footable foo_table_10952 ninja_table_unique_id_1002753620_10952 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse2\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0665\u0669\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse2\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12964\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_1\" data-footable_id=\"12964\" data-filter-delay=\"1000\" aria-label=\"\u0633\u0627\u0644 \u0661\u0663\u0665\u0669\"            id=\"footable_12964\"\n           data-unique_identifier=\"ninja_table_unique_id_1781856416_12964\"\n           class=\" foo-table ninja_footable foo_table_12964 ninja_table_unique_id_1781856416_12964 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                            <col class=\"ninja_column_12 \">\n                            <col class=\"ninja_column_13 \">\n                            <col class=\"ninja_column_14 \">\n                            <col class=\"ninja_column_15 \">\n                            <col class=\"ninja_column_16 \">\n                            <col class=\"ninja_column_17 \">\n                            <col class=\"ninja_column_18 \">\n                            <col class=\"ninja_column_19 \">\n                            <col class=\"ninja_column_20 \">\n                            <col class=\"ninja_column_21 \">\n                            <col class=\"ninja_column_22 \">\n                            <col class=\"ninja_column_23 \">\n                            <col class=\"ninja_column_24 \">\n                            <col class=\"ninja_column_25 \">\n                            <col class=\"ninja_column_26 \">\n                            <col class=\"ninja_column_27 \">\n                            <col class=\"ninja_column_28 \">\n                            <col class=\"ninja_column_29 \">\n                            <col class=\"ninja_column_30 \">\n                            <col class=\"ninja_column_31 \">\n                            <col class=\"ninja_column_32 \">\n                            <col class=\"ninja_column_33 \">\n                            <col class=\"ninja_column_34 \">\n                            <col class=\"ninja_column_35 \">\n                            <col class=\"ninja_column_36 \">\n                            <col class=\"ninja_column_37 \">\n                            <col class=\"ninja_column_38 \">\n                            <col class=\"ninja_column_39 \">\n                            <col class=\"ninja_column_40 \">\n                            <col class=\"ninja_column_41 \">\n                            <col class=\"ninja_column_42 \">\n                            <col class=\"ninja_column_43 \">\n                            <col class=\"ninja_column_44 \">\n                            <col class=\"ninja_column_45 \">\n                            <col class=\"ninja_column_46 \">\n                            <col class=\"ninja_column_47 \">\n                            <col class=\"ninja_column_48 \">\n                            <col class=\"ninja_column_49 \">\n                            <col class=\"ninja_column_50 \">\n                            <col class=\"ninja_column_51 \">\n                            <col class=\"ninja_column_52 \">\n                            <col class=\"ninja_column_53 \">\n                            <col class=\"ninja_column_54 \">\n                            <col class=\"ninja_column_55 \">\n                            <col class=\"ninja_column_56 \">\n                            <col class=\"ninja_column_57 \">\n                            <col class=\"ninja_column_58 \">\n                            <col class=\"ninja_column_59 \">\n                            <col class=\"ninja_column_60 \">\n                            <col class=\"ninja_column_61 \">\n                            <col class=\"ninja_column_62 \">\n                            <col class=\"ninja_column_63 \">\n                            <col class=\"ninja_column_64 \">\n                            <col class=\"ninja_column_65 \">\n                            <col class=\"ninja_column_66 \">\n                            <col class=\"ninja_column_67 \">\n                            <col class=\"ninja_column_68 \">\n                            <col class=\"ninja_column_69 \">\n                            <col class=\"ninja_column_70 \">\n                            <col class=\"ninja_column_71 \">\n                            <col class=\"ninja_column_72 \">\n                            <col class=\"ninja_column_73 \">\n                            <col class=\"ninja_column_74 \">\n                            <col class=\"ninja_column_75 \">\n                            <col class=\"ninja_column_76 \">\n                            <col class=\"ninja_column_77 \">\n                            <col class=\"ninja_column_78 \">\n                            <col class=\"ninja_column_79 \">\n                            <col class=\"ninja_column_80 \">\n                            <col class=\"ninja_column_81 \">\n                            <col class=\"ninja_column_82 \">\n                            <col class=\"ninja_column_83 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse3\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0660\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse3\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12475\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_2\" data-footable_id=\"12475\" data-filter-delay=\"1000\" aria-label=\"\u0633\u0627\u0644 \u0661\u0663\u0666\u0660\"            id=\"footable_12475\"\n           data-unique_identifier=\"ninja_table_unique_id_965065101_12475\"\n           class=\" foo-table ninja_footable foo_table_12475 ninja_table_unique_id_965065101_12475 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse4\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0661\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse4\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12494\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_3\" data-footable_id=\"12494\" data-filter-delay=\"1000\" aria-label=\"\u0633\u0627\u0644 \u0661\u0663\u0666\u0661\"            id=\"footable_12494\"\n           data-unique_identifier=\"ninja_table_unique_id_2104395218_12494\"\n           class=\" foo-table ninja_footable foo_table_12494 ninja_table_unique_id_2104395218_12494 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse5\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0662 \u0628\u062e\u0634 \u06cc\u06a9\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse5\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12498\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_4\" data-footable_id=\"12498\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0662\u0628\u062e\u0634 \u06cc\u06a9\"            id=\"footable_12498\"\n           data-unique_identifier=\"ninja_table_unique_id_12319439_12498\"\n           class=\" foo-table ninja_footable foo_table_12498 ninja_table_unique_id_12319439_12498 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse6\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0662 \u0628\u062e\u0634 \u062f\u0648\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse6\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12506\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_5\" data-footable_id=\"12506\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0662 \u0628\u062e\u0634 \u062f\u0648\"            id=\"footable_12506\"\n           data-unique_identifier=\"ninja_table_unique_id_587275552_12506\"\n           class=\" foo-table ninja_footable foo_table_12506 ninja_table_unique_id_587275552_12506 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse7\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0663\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse7\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9987\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_6\" data-footable_id=\"9987\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0663\"            id=\"footable_9987\"\n           data-unique_identifier=\"ninja_table_unique_id_1250963096_9987\"\n           class=\" foo-table ninja_footable foo_table_9987 ninja_table_unique_id_1250963096_9987 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse8\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0664\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse8\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_8125\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_7\" data-footable_id=\"8125\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0664\"            id=\"footable_8125\"\n           data-unique_identifier=\"ninja_table_unique_id_639508628_8125\"\n           class=\" foo-table ninja_footable foo_table_8125 ninja_table_unique_id_639508628_8125 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse9\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0665\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse9\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9968\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_8\" data-footable_id=\"9968\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0665\"            id=\"footable_9968\"\n           data-unique_identifier=\"ninja_table_unique_id_1655501920_9968\"\n           class=\" foo-table ninja_footable foo_table_9968 ninja_table_unique_id_1655501920_9968 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse10\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0666\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse10\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9966\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_9\" data-footable_id=\"9966\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0666\"            id=\"footable_9966\"\n           data-unique_identifier=\"ninja_table_unique_id_1619961408_9966\"\n           class=\" foo-table ninja_footable foo_table_9966 ninja_table_unique_id_1619961408_9966 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse11\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0667\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse11\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_11575\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_10\" data-footable_id=\"11575\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0667 \u0628\u0627 \u0639\u0635\u0631 \u0646\u0648\"            id=\"footable_11575\"\n           data-unique_identifier=\"ninja_table_unique_id_1245450502_11575\"\n           class=\" foo-table ninja_footable foo_table_11575 ninja_table_unique_id_1245450502_11575 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse12\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0668\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse12\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9977\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_11\" data-footable_id=\"9977\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0668\"            id=\"footable_9977\"\n           data-unique_identifier=\"ninja_table_unique_id_1734482953_9977\"\n           class=\" foo-table ninja_footable foo_table_9977 ninja_table_unique_id_1734482953_9977 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse13\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0666\u0669\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse13\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9460\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_12\" data-footable_id=\"9460\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0666\u0669\"            id=\"footable_9460\"\n           data-unique_identifier=\"ninja_table_unique_id_1603512987_9460\"\n           class=\" foo-table ninja_footable foo_table_9460 ninja_table_unique_id_1603512987_9460 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse14\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0660\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse14\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_8073\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_13\" data-footable_id=\"8073\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0660\"            id=\"footable_8073\"\n           data-unique_identifier=\"ninja_table_unique_id_1383738703_8073\"\n           class=\" foo-table ninja_footable foo_table_8073 ninja_table_unique_id_1383738703_8073 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse15\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0661\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse15\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9955\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_14\" data-footable_id=\"9955\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0661\"            id=\"footable_9955\"\n           data-unique_identifier=\"ninja_table_unique_id_838929938_9955\"\n           class=\" foo-table ninja_footable foo_table_9955 ninja_table_unique_id_838929938_9955 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse16\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0662\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse16\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9853\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_15\" data-footable_id=\"9853\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0662\"            id=\"footable_9853\"\n           data-unique_identifier=\"ninja_table_unique_id_1426981488_9853\"\n           class=\" foo-table ninja_footable foo_table_9853 ninja_table_unique_id_1426981488_9853 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse17\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0663\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse17\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9455\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_16\" data-footable_id=\"9455\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0663\"            id=\"footable_9455\"\n           data-unique_identifier=\"ninja_table_unique_id_231144200_9455\"\n           class=\" foo-table ninja_footable foo_table_9455 ninja_table_unique_id_231144200_9455 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse18\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0664\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse18\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9856\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_17\" data-footable_id=\"9856\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0664\"            id=\"footable_9856\"\n           data-unique_identifier=\"ninja_table_unique_id_913870852_9856\"\n           class=\" foo-table ninja_footable foo_table_9856 ninja_table_unique_id_913870852_9856 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse19\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0665\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse19\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_6860\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_18\" data-footable_id=\"6860\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0665\"            id=\"footable_6860\"\n           data-unique_identifier=\"ninja_table_unique_id_1452789324_6860\"\n           class=\" foo-table ninja_footable foo_table_6860 ninja_table_unique_id_1452789324_6860 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse20\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0666\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse20\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_6867\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_19\" data-footable_id=\"6867\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0666\"            id=\"footable_6867\"\n           data-unique_identifier=\"ninja_table_unique_id_1541251899_6867\"\n           class=\" foo-table ninja_footable foo_table_6867 ninja_table_unique_id_1541251899_6867 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse21\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0667\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse21\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_6875\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_20\" data-footable_id=\"6875\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0667\"            id=\"footable_6875\"\n           data-unique_identifier=\"ninja_table_unique_id_690912052_6875\"\n           class=\" foo-table ninja_footable foo_table_6875 ninja_table_unique_id_690912052_6875 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse22\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0667\u0668\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse22\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_8241\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_21\" data-footable_id=\"8241\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0667\u0668\"            id=\"footable_8241\"\n           data-unique_identifier=\"ninja_table_unique_id_247656086_8241\"\n           class=\" foo-table ninja_footable foo_table_8241 ninja_table_unique_id_247656086_8241 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse23\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0668\u0660\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse23\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9981\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_22\" data-footable_id=\"9981\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0668\u0660\"            id=\"footable_9981\"\n           data-unique_identifier=\"ninja_table_unique_id_1923722344_9981\"\n           class=\" foo-table ninja_footable foo_table_9981 ninja_table_unique_id_1923722344_9981 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse24\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0668\u0661\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse24\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_10695\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_23\" data-footable_id=\"10695\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0668\u0661\"            id=\"footable_10695\"\n           data-unique_identifier=\"ninja_table_unique_id_394552703_10695\"\n           class=\" foo-table ninja_footable foo_table_10695 ninja_table_unique_id_394552703_10695 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse25\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0668\u0662\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse25\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_8069\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_24\" data-footable_id=\"8069\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0668\u0662\"            id=\"footable_8069\"\n           data-unique_identifier=\"ninja_table_unique_id_1366568071_8069\"\n           class=\" foo-table ninja_footable foo_table_8069 ninja_table_unique_id_1366568071_8069 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse26\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0668\u0668\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse26\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_7827\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_25\" data-footable_id=\"7827\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0668\u0668\"            id=\"footable_7827\"\n           data-unique_identifier=\"ninja_table_unique_id_610578708_7827\"\n           class=\" foo-table ninja_footable foo_table_7827 ninja_table_unique_id_610578708_7827 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse27\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0668\u0669\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse27\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3708\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_26\" data-footable_id=\"3708\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0668\u0669\"            id=\"footable_3708\"\n           data-unique_identifier=\"ninja_table_unique_id_806967109_3708\"\n           class=\" foo-table ninja_footable foo_table_3708 ninja_table_unique_id_806967109_3708 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse28\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0662\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse28\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3711\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_27\" data-footable_id=\"3711\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0662\"            id=\"footable_3711\"\n           data-unique_identifier=\"ninja_table_unique_id_209294178_3711\"\n           class=\" foo-table ninja_footable foo_table_3711 ninja_table_unique_id_209294178_3711 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse29\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0664\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse29\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3763\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_28\" data-footable_id=\"3763\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0664\"            id=\"footable_3763\"\n           data-unique_identifier=\"ninja_table_unique_id_1051672693_3763\"\n           class=\" foo-table ninja_footable foo_table_3763 ninja_table_unique_id_1051672693_3763 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse30\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0665\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse30\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3764\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_29\" data-footable_id=\"3764\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0665\"            id=\"footable_3764\"\n           data-unique_identifier=\"ninja_table_unique_id_1512189820_3764\"\n           class=\" foo-table ninja_footable foo_table_3764 ninja_table_unique_id_1512189820_3764 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse31\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0666\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse31\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_4656\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_30\" data-footable_id=\"4656\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0666\"            id=\"footable_4656\"\n           data-unique_identifier=\"ninja_table_unique_id_1100004924_4656\"\n           class=\" foo-table ninja_footable foo_table_4656 ninja_table_unique_id_1100004924_4656 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse32\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0667\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse32\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3714\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_31\" data-footable_id=\"3714\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0667\"            id=\"footable_3714\"\n           data-unique_identifier=\"ninja_table_unique_id_314931027_3714\"\n           class=\" foo-table ninja_footable foo_table_3714 ninja_table_unique_id_314931027_3714 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse33\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0663\u0669\u0669\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse33\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_3717\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_32\" data-footable_id=\"3717\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0663\u0669\u0669\"            id=\"footable_3717\"\n           data-unique_identifier=\"ninja_table_unique_id_304171935_3717\"\n           class=\" foo-table ninja_footable foo_table_3717 ninja_table_unique_id_304171935_3717 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse34\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0664\u0660\u0660\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse34\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_9342\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_33\" data-footable_id=\"9342\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0664\u0660\u0660\"            id=\"footable_9342\"\n           data-unique_identifier=\"ninja_table_unique_id_1474433498_9342\"\n           class=\" foo-table ninja_footable foo_table_9342 ninja_table_unique_id_1474433498_9342 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse35\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0664\u0660\u0661\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse35\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_11293\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_34\" data-footable_id=\"11293\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644 \u0661\u0664\u0660\u0661\"            id=\"footable_11293\"\n           data-unique_identifier=\"ninja_table_unique_id_57258135_11293\"\n           class=\" foo-table ninja_footable foo_table_11293 ninja_table_unique_id_57258135_11293 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse36\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0664\u0660\u0662\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse36\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse37\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0633\u0627\u0644 \u0661\u0664\u0660\u0663\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse37\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_12030\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_35\" data-footable_id=\"12030\" data-filter-delay=\"1000\" aria-label=\"\u0633\u0627\u0644 \u0661\u0664\u0660\u0663\"            id=\"footable_12030\"\n           data-unique_identifier=\"ninja_table_unique_id_471109605_12030\"\n           class=\" foo-table ninja_footable foo_table_12030 ninja_table_unique_id_471109605_12030 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"wpsm_panel wpsm_panel-default\">\r\n\t\t\t\t\t\t<div class=\"wpsm_panel-heading\" role=\"tab\" >\r\n\t\t\t\t\t\t  <h4 class=\"wpsm_panel-title\">\r\n\t\t\t\t\t\t\t<a  class=\"collapsed\"  data-toggle=\"collapse\" data-parent=\"\" href=\"javascript:void(0)\" data-target=\"#ac_5031_collapse38\" onclick=\"do_resize()\">\r\n\t\t\t\t\t\t\t\t \r\n\t\t\t\t\t\t\t\t<span class=\"ac_title_class\">\r\n\t\t\t\t\t\t\t\t\t\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644\u0647\u0627\u06cc \u0646\u0627\u0645\u0639\u0644\u0648\u0645\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t  <\/h4>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div id=\"ac_5031_collapse38\" class=\"wpsm_panel-collapse collapse in\"  >\r\n\t\t\t\t\t\t  <div class=\"wpsm_panel-body\">\r\n\t\t\t\t\t\t\t<div id=\"footable_parent_8431\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent bootstrap3 \">\n                        <div\n                class=\"table_description footable_description\"><\/div>\n                    <table data-ninja_table_instance=\"ninja_table_instance_36\" data-footable_id=\"8431\" data-filter-delay=\"1000\" aria-label=\"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 \u0633\u0627\u0644\u0647\u0627\u06cc \u0646\u0627\u0645\u0639\u0644\u0648\u0645\"            id=\"footable_8431\"\n           data-unique_identifier=\"ninja_table_unique_id_654513392_8431\"\n           class=\" foo-table ninja_footable foo_table_8431 ninja_table_unique_id_654513392_8431 table  nt_type_ajax_table table-hover vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                            <col class=\"ninja_column_4 \">\n                            <col class=\"ninja_column_5 \">\n                            <col class=\"ninja_column_6 \">\n                            <col class=\"ninja_column_7 \">\n                            <col class=\"ninja_column_8 \">\n                            <col class=\"ninja_column_9 \">\n                            <col class=\"ninja_column_10 \">\n                            <col class=\"ninja_column_11 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n\t\t\t\t\t\t  <\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\r\n<script type=\"text\/javascript\">\r\n\t\r\n\t\tfunction do_resize(){\r\n\r\n\t\t\tvar width=jQuery( '.wpsm_panel .wpsm_panel-body iframe' ).width();\r\n\t\t\tvar height=jQuery( '.wpsm_panel .wpsm_panel-body iframe' ).height();\r\n\r\n\t\t\tvar toggleSize = true;\r\n\t\t\tjQuery('iframe').animate({\r\n\t\t\t    width: toggleSize ? width : 640,\r\n\t\t\t    height: toggleSize ? height : 360\r\n\t\t\t  }, 250);\r\n\r\n\t\t\t  toggleSize = !toggleSize;\r\n\t\t}\r\n\t\t\r\n<\/script>\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u0633\u0627\u0645\u06cc \u0648 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u06d5 \u0627\u0639\u062f\u0627\u0645\u200c\u0634\u062f\u06af\u0627\u0646 \u0633\u0631\u0627\u0633\u0631 \u0645\u0631\u062f\u0645 \u06a9\u0631\u062f\u0633\u062a\u0627\u0646 \u0627\u0632 \u0627\u06cc\u0644\u0627\u0645 \u062a\u0627 \u0645\u0627\u06a9\u0648 \u0648 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0633\u0631 \u06a9\u0627\u0631 \u0622\u0645\u062f\u0646 \u0631\u0698\u06cc\u0645 \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0635\u062f\u0647\u0627 \u0646\u0641\u0631 \u0628\u06cc\u06af\u0646\u0627\u0647 \u0627\u0639\u062f\u0627\u0645 \u0634\u062f\u06d5\u0627\u0646\u062f. \u06a9\u0634\u062a\u0627\u0631\u0647\u0627\u06cc \u062f\u0633\u062a\u0647 \u062c\u0645\u0639\u06cc \u06a9\u0647 \u0628\u0647 \u0634\u06cc\u0648\u0647\u200c\u06cc \u0633\u06cc\u0633\u062a\u06cc\u0645\u0627\u062a\u06cc\u06a9 \u0648 \u0628\u0631\u0646\u0627\u0645\u06d5\u0631\u06cc\u0632\u06cc \u0634\u062f\u0647 \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u060c \u0647\u06cc\u0686 \u06af\u0648\u0646\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0648\u0627\u0636\u062d \u062f\u0631\u0628\u0627\u0631\u06d5 \u0627\u06cc\u0646 \u062c\u0646\u0627\u06cc\u062a\u0647\u0627 \u062a\u0627 \u0628\u06d5 \u0627\u0645\u0631\u0648\u0632 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5916,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"slim_seo":{"title":"\u0632\u0646\u062f\u06d5\u06cc\u0627\u062f\u0627\u0646 - \u0646\u06d5\u0645\u0631\u0627\u0646","description":""},"footnotes":""},"class_list":["post-5022","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/pages\/5022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/comments?post=5022"}],"version-history":[{"count":21,"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/pages\/5022\/revisions"}],"predecessor-version":[{"id":6449,"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/pages\/5022\/revisions\/6449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/media\/5916"}],"wp:attachment":[{"href":"https:\/\/nemiran.com\/roj\/wp-json\/wp\/v2\/media?parent=5022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}